{"id":2302,"date":"2021-01-19T14:30:24","date_gmt":"2021-01-19T14:30:24","guid":{"rendered":"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/?p=2302"},"modified":"2025-09-17T12:49:24","modified_gmt":"2025-09-17T12:49:24","slug":"agua-dulce","status":"publish","type":"post","link":"https:\/\/coloniaavellaneda.gob.ar\/web\/agua-dulce\/","title":{"rendered":"Agua Dulce"},"content":{"rendered":"<figure><img decoding=\"async\" src=\"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/02\/140796906_3702343096491169_1382633478998893162_n-768x512.jpg\" alt=\"140796906_3702343096491169_1382633478998893162_n\" \/><\/figure>\n<figure><img decoding=\"async\" src=\"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/02\/140081028_3702343186491160_4249014033232491458_n-768x511.jpg\" alt=\"140081028_3702343186491160_4249014033232491458_n\" \/><\/figure>\n<figure><img decoding=\"async\" src=\"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/02\/140038481_3702343256491153_436998132822348707_n-768x514.jpg\" alt=\"140038481_3702343256491153_436998132822348707_n\" \/><\/figure>\n<p>\t\t\t\t\t\tAnterior<br \/>\n\t\t\t\t\t\tSiguiente<br \/>\n\t\tSeguimos a paso firme con el objetivo de traer el agua dulce desde Paran\u00e1. \u00a0Convenimos ceder a Obras Sanitarias de Entre R\u00edos el espacio urbano necesario para la realizaci\u00f3n de tan ansiada obra\u00bb.\u00a0\u00a1Gracias Gobernador Gustavo Bordet!\u00a1Gracias Presidente Alberto Fern\u00e1ndez!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seguimos a paso firme con el objetivo de traer el agua dulce desde Paran\u00e1. <\/p>\n","protected":false},"author":1,"featured_media":2305,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[15],"tags":[],"class_list":["post-2302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipio"],"_links":{"self":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/2302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/comments?post=2302"}],"version-history":[{"count":1,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/2302\/revisions"}],"predecessor-version":[{"id":6258,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/2302\/revisions\/6258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/media?parent=2302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/categories?post=2302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/tags?post=2302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}