{"id":2316,"date":"2021-02-03T20:49:14","date_gmt":"2021-02-03T20:49:14","guid":{"rendered":"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/?p=2316"},"modified":"2021-02-03T20:49:14","modified_gmt":"2021-02-03T20:49:14","slug":"dificultad-en-la-distribucion-de-agua","status":"publish","type":"post","link":"https:\/\/coloniaavellaneda.gob.ar\/web\/dificultad-en-la-distribucion-de-agua\/","title":{"rendered":"Dificultad en la distribuci\u00f3n de agua"},"content":{"rendered":"<p>Informamos a los vecinos que debido a las condiciones clim\u00e1ticas de los \u00faltimos d\u00edas se est\u00e1 dificultando llevar el bid\u00f3n de agua dulce a cada domicilio, por lo que se dispuso una guardia, a partir del jueves 4 de febrero, de 07:00 a 17:00hs para quien pueda acercarse y retirar el bid\u00f3n de agua desde el sal\u00f3n de la Cooperativa de Agua de Colonia Avellaneda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Retirar el bid\u00f3n de agua desde el sal\u00f3n de la Cooperativa de Agua de Colonia Avellaneda.<\/p>\n","protected":false},"author":1,"featured_media":2317,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[15],"tags":[29],"class_list":["post-2316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipio","tag-agua"],"_links":{"self":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/2316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/comments?post=2316"}],"version-history":[{"count":0,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/2316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/media?parent=2316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/categories?post=2316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/tags?post=2316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}