{"id":2579,"date":"2021-02-09T18:58:08","date_gmt":"2021-02-09T18:58:08","guid":{"rendered":"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/?p=2579"},"modified":"2021-02-09T18:58:08","modified_gmt":"2021-02-09T18:58:08","slug":"torneo-libre-de-tenis-de-mesa","status":"publish","type":"post","link":"https:\/\/coloniaavellaneda.gob.ar\/web\/torneo-libre-de-tenis-de-mesa\/","title":{"rendered":"Torneo Libre de Tenis de Mesa"},"content":{"rendered":"<h2>Torneo Libre de Tenis de Mesa<\/h2>\n<p>\t\tTorneo Libre de Tenis de Mesa para todas la edades y niveles.\u00a0Premios para los tres primeros puestos.<\/p>\n<ul>\n<li dir=\"auto\">D\u00edas:\n<ul>\n<li dir=\"auto\">Domingo 14\/02: Pr\u00e1ctica libre por la tarde<\/li>\n<li dir=\"auto\">Lunes 15\/02: Torneo a partir de las 16hs<\/li>\n<\/ul>\n<\/li>\n<li dir=\"auto\">Inscripci\u00f3n: Gratuita<\/li>\n<li dir=\"auto\">Lugar: Prado Espa\u00f1ol<\/li>\n<li dir=\"auto\">Te prestamos la paleta <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tda\/1\/16\/1f3d3.png\" alt=\"&#x1f3d3;\" width=\"16\" height=\"16\" \/><\/li>\n<li dir=\"auto\">Por consultas: <strong>3435362691<\/strong><\/li>\n<li dir=\"auto\">Organiza:\n<ul>\n<li dir=\"auto\">Aspatem @aspatem_parana\u00a0<\/li>\n<li dir=\"auto\">\u00c1rea de Deportes Municipio de Colonia Avellaneda.-<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>(Para personas que no hayan disputado torneos de liga dos orilla de tenis de mesa).\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para todas las edades y niveles<\/p>\n","protected":false},"author":1,"featured_media":2580,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[7,21],"tags":[],"class_list":["post-2579","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-prado_espanol"],"_links":{"self":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/2579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/comments?post=2579"}],"version-history":[{"count":0,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/2579\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/media?parent=2579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/categories?post=2579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/tags?post=2579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}