{"id":3023,"date":"2021-03-23T20:42:10","date_gmt":"2021-03-23T20:42:10","guid":{"rendered":"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/?p=3023"},"modified":"2021-03-23T20:42:10","modified_gmt":"2021-03-23T20:42:10","slug":"vuelve-el-hockey","status":"publish","type":"post","link":"https:\/\/coloniaavellaneda.gob.ar\/web\/vuelve-el-hockey\/","title":{"rendered":"Vuelve el Hockey"},"content":{"rendered":"<h2>Vuelve el HOCKEY a Colonia Avellaneda<\/h2>\n<p>\t\tDesde el \u00c1rea de Deportes se informa a todos los vecinos de nuestra ciudad los nuevos horarios para este 2021 de Hockey.\u00a0Los esperamos en el Prado Espa\u00f1ol<br \/>\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"720\" height=\"522\" src=\"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/03\/hockey.jpg\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/03\/hockey.jpg 720w, http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/03\/hockey-300x218.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vuelve el HOCKEY a Colonia Avellaneda Desde el \u00c1rea de Deportes se informa a todos los vecinos de nuestra ciudad los nuevos horarios para este 2021 de Hockey.\u00a0Los esperamos en el Prado Espa\u00f1ol<\/p>\n","protected":false},"author":1,"featured_media":3024,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[7,21],"tags":[],"class_list":["post-3023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-prado_espanol"],"_links":{"self":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/3023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/comments?post=3023"}],"version-history":[{"count":0,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/3023\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/media?parent=3023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/categories?post=3023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/tags?post=3023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}