{"id":3108,"date":"2021-04-08T18:34:15","date_gmt":"2021-04-08T18:34:15","guid":{"rendered":"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/?p=3108"},"modified":"2021-04-08T18:34:15","modified_gmt":"2021-04-08T18:34:15","slug":"vencimiento-de-las-tasas-municipales","status":"publish","type":"post","link":"https:\/\/coloniaavellaneda.gob.ar\/web\/vencimiento-de-las-tasas-municipales\/","title":{"rendered":"Vencimiento de las Tasas Municipales"},"content":{"rendered":"<h2>Atenci\u00f3n vecinos<\/h2>\n<p>\t\tLes acercamos los pr\u00f3ximos vencimiento de las Tasas Municipales.\u00a0Informamos que el \u00fanico lugar donde pueden pagar las mismas es la Caja Municipal, de igual manera pueden enviar un correo a <strong>rentas@coloniaavellaneda.gob.ar <\/strong>y solicitar el CBU para realizar una transferencia.<br \/>\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"526\" height=\"526\" src=\"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/04\/171016887_3921620151230128_2321317028242220254_n.jpg\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/04\/171016887_3921620151230128_2321317028242220254_n.jpg 526w, http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/04\/171016887_3921620151230128_2321317028242220254_n-300x300.jpg 300w, http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/04\/171016887_3921620151230128_2321317028242220254_n-150x150.jpg 150w\" sizes=\"(max-width: 526px) 100vw, 526px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atenci\u00f3n vecinos Les acercamos los pr\u00f3ximos vencimiento de las Tasas Municipales.\u00a0Informamos que el \u00fanico lugar donde pueden pagar las mismas es la Caja Municipal, de igual manera pueden enviar un correo a rentas@coloniaavellaneda.gob.ar y solicitar el CBU para realizar una transferencia.<\/p>\n","protected":false},"author":1,"featured_media":3109,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[15],"tags":[],"class_list":["post-3108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipio"],"_links":{"self":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/3108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/comments?post=3108"}],"version-history":[{"count":0,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/3108\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/media?parent=3108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/categories?post=3108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/tags?post=3108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}