{"id":3294,"date":"2021-05-16T09:57:23","date_gmt":"2021-05-16T09:57:23","guid":{"rendered":"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/?p=3294"},"modified":"2021-05-16T09:57:23","modified_gmt":"2021-05-16T09:57:23","slug":"nueva-colecta-de-sangre","status":"publish","type":"post","link":"https:\/\/coloniaavellaneda.gob.ar\/web\/nueva-colecta-de-sangre\/","title":{"rendered":"Nueva Colecta de Sangre"},"content":{"rendered":"<p>El \u00c1rea de Promoci\u00f3n y Desarrollo social informa que se llevar\u00e1 a cabo la campa\u00f1a de Donaci\u00f3n de Sangre por parte del Programa Provincial de Hemoterapia.\u00a0Donar sangre salva vidas, por eso invitamos a todos los vecinos a hacerlo acerc\u00e1ndose el d\u00eda 19 de mayo de 07:30 a 11:30 a Mariano Moreno, frente a la plaza San Mart\u00edn.La misma se realizar\u00e1 por orden de llegada.En caso de tomar medicaciones realizarlo con normalidad.Desayunar normalmente.\u00a0Por consultas al 3435253330<br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"508\" height=\"720\" src=\"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/05\/186481255_4032824363443039_3433771921756087350_n.jpg\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/05\/186481255_4032824363443039_3433771921756087350_n.jpg 508w, http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/05\/186481255_4032824363443039_3433771921756087350_n-212x300.jpg 212w\" sizes=\"(max-width: 508px) 100vw, 508px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este 19 de mayo de 07:30 a 11:30 en el SUM de la Municipalidad.<\/p>\n","protected":false},"author":1,"featured_media":3295,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[24],"tags":[],"class_list":["post-3294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud"],"_links":{"self":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/3294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/comments?post=3294"}],"version-history":[{"count":0,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/3294\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/media?parent=3294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/categories?post=3294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/tags?post=3294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}