{"id":3420,"date":"2021-05-23T15:41:47","date_gmt":"2021-05-23T15:41:47","guid":{"rendered":"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/?p=3420"},"modified":"2021-05-23T15:41:47","modified_gmt":"2021-05-23T15:41:47","slug":"nuevas-medidas-2","status":"publish","type":"post","link":"https:\/\/coloniaavellaneda.gob.ar\/web\/nuevas-medidas-2\/","title":{"rendered":"Nuevas Medidas"},"content":{"rendered":"<h2>Nuevas medidas preventivas para reducir riesgos de Covid-19 en Colonia Avellaneda.<\/h2>\n<p>*Se restringe la circulaci\u00f3n en la ciudad de Colonia Avellaneda, seg\u00fan lo dispuesto por Decreto Nacional.&nbsp;*Quedar\u00e1n suspendidas las actividades sociales, educativas, religiosas y deportivas en forma presencial.&nbsp;* S\u00f3lo se podr\u00e1 circular en las cercan\u00edas del domicilio, entre las 6 de la ma\u00f1ana y las 18hs por razones especialmente autorizadas (aprovisionarse de art\u00edculos de limpieza, medicamentos y alimentos y otros art\u00edculos de necesidad en los comercios esenciales)&nbsp;*Los comercios No esenciales y locales gastron\u00f3micos s\u00f3lo podr\u00e1n trabajar bajo modalidad delivery y retiro en puerta hasta las 18hs (permitiendo desde las 18hs hasta las 23hs gastron\u00f3micas y en modalidad delivery)&nbsp;*Esta permitido realizar salidas de esparcimiento en espacios p\u00fablicos de cercan\u00eda, al aire libre, dentro de los horarios habilitados para circular, y dando cumplimiento a los protocolos vigentes.&nbsp;Les recordamos que los trabajadores y las trabajadoras esenciales pueden obtener m\u00e1s informaci\u00f3n sobre los permisos en <a tabindex=\"0\" role=\"link\" href=\"https:\/\/www.argentina.gob.ar\/jefatura\/innovacion-publica\/acciones-coronavirus\/aplicacion-y-tableros-de-gestion?fbclid=IwAR2W0mSBoqFFQPvEDskybj9DcXa5QSPkhsILtXF8irVi1zgQpC7RTZHkwXo\" target=\"_blank\" rel=\"nofollow noopener\">https:\/\/www.argentina.gob.ar\/&#8230;\/aplicacion-y-tableros-de&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Po Decreto Nacional hasta el d\u00eda 30\/05\/21<\/p>\n","protected":false},"author":1,"featured_media":3421,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[11,15],"tags":[],"class_list":["post-3420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-municipio"],"_links":{"self":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/3420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/comments?post=3420"}],"version-history":[{"count":0,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/3420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/media?parent=3420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/categories?post=3420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/tags?post=3420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}