{"id":3609,"date":"2021-06-17T10:28:57","date_gmt":"2021-06-17T10:28:57","guid":{"rendered":"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/?p=3609"},"modified":"2021-06-17T10:28:57","modified_gmt":"2021-06-17T10:28:57","slug":"adjudicacion-de-obra","status":"publish","type":"post","link":"https:\/\/coloniaavellaneda.gob.ar\/web\/adjudicacion-de-obra\/","title":{"rendered":"Adjudicaci\u00f3n de Obra"},"content":{"rendered":"<h3>Adjudicaci\u00f3n de obra en nuestra ciudad<\/h3>\n<p>Con mucha satisfacci\u00f3n anunciamos que a trav\u00e9s del decreto <strong>1468\/2021<\/strong>, nuestro Gobernador <strong>Gustavo Bordet<\/strong> dio adjudicaci\u00f3n a la obra de Acondicionamiento y recuperaci\u00f3n de lagunas de tratamiento de efluentes en nuestra ciudad, una obra necesaria para todos los vecinos y todas las vecinas, y que baja significativamente el impacto ambiental de la ciudad.&nbsp;Se trata de un proyecto que viene a solucionar un problema que hoy tiene nuestra ciudad, y que gracias al Gobierno Provincial, quien invirti\u00f3 m\u00e1s de 50 millones de pesos, los Colonienses tendr\u00e1n una vida mejor.&nbsp;Agradecemos al Gobernador, qui\u00e9n siempre ha acompa\u00f1ado las gestiones de nuestro Municipio, comprometi\u00e9ndose desde el primer d\u00eda con los vecinos y las vecinas de nuestra Colonia.&nbsp;La obra fue adjudicada mediante licitaci\u00f3n publica 02\/2021 DPOSER a la empresa Constructora OIC.SA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acondicionamiento y recuperaci\u00f3n de lagunas de tratamiento de efluentes de la ciudad.<\/p>\n","protected":false},"author":1,"featured_media":3610,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[15],"tags":[],"class_list":["post-3609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipio"],"_links":{"self":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/3609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/comments?post=3609"}],"version-history":[{"count":0,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/3609\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/media?parent=3609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/categories?post=3609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/tags?post=3609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}