{"id":4053,"date":"2021-08-17T12:03:37","date_gmt":"2021-08-17T12:03:37","guid":{"rendered":"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/?p=4053"},"modified":"2021-08-17T12:03:37","modified_gmt":"2021-08-17T12:03:37","slug":"mes-de-las-infancias","status":"publish","type":"post","link":"https:\/\/coloniaavellaneda.gob.ar\/web\/mes-de-las-infancias\/","title":{"rendered":"Mes de las infancias"},"content":{"rendered":"<h2>Sorteo de dibujos por el  mes de las infancias<\/h2>\n<p>\t\tTe invitamos a celebrar el mes de las infancias con un sorteo de dibujos para ni\u00f1as y ni\u00f1os residentes de Colonia Avellaneda, escolarizados.\u00a0<strong>Con la tem\u00e1tica <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tf8\/1\/16\/267b.png\" alt=\"&#x267b;&#xfe0f;\" width=\"16\" height=\"16\" \/> \u00abcuidemos el ambiente\u00bb podes realizar un dibujo que represente como trabajas d\u00eda a d\u00eda el cuidado de nuestro planeta<\/strong>.<br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"717\" height=\"540\" src=\"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/08\/225383235_4288253171233489_909854393854311557_n.jpg\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/08\/225383235_4288253171233489_909854393854311557_n.jpg 717w, http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/08\/225383235_4288253171233489_909854393854311557_n-300x226.jpg 300w\" sizes=\"(max-width: 717px) 100vw, 717px\" \/><br \/>\n\t\tPueden acercar sus dibujos a los siguientes puntos de recolecci\u00f3n:- Prado Espa\u00f1ol- Polideportivo Malvinas Argentinas- Escuelas Primarias<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li dir=\"auto\">Escuela N\u00b0 170<\/li>\n<li dir=\"auto\">Escuela N\u00b0 212<\/li>\n<li dir=\"auto\">Complejo Educativo Santa Teresa<\/li>\n<li>Escuela N\u00b0 34<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p style=\"padding-left: 40px;\">&#8211; Cami\u00f3n del agua<\/p>\n<p>&#8211; Palacio municipal\u00a0Por consultas sobre entrega, pueden comunicarse al tel\u00e9fono <strong>+54 9 343 404-2491<\/strong>.\u00a0El sorteo de los mismos se realizar\u00e1 en vivo por Cadena de Multimedios Metropolitana el d\u00eda <strong>Domingo 29 de agosto<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sorteo de dibujos por el mes de las infancias Te invitamos a celebrar el mes de las infancias con un sorteo de dibujos para ni\u00f1as y ni\u00f1os residentes de Colonia Avellaneda, escolarizados.\u00a0Con la tem\u00e1tica \u00abcuidemos el ambiente\u00bb podes realizar un dibujo que represente como trabajas d\u00eda a d\u00eda el cuidado de nuestro planeta. Pueden acercar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4054,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[16],"tags":[],"class_list":["post-4053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ninez-adolecencia-familia"],"_links":{"self":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/4053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/comments?post=4053"}],"version-history":[{"count":0,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/4053\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/media?parent=4053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/categories?post=4053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/tags?post=4053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}