{"id":4326,"date":"2021-09-11T01:05:25","date_gmt":"2021-09-11T01:05:25","guid":{"rendered":"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/?p=4326"},"modified":"2021-09-11T01:05:25","modified_gmt":"2021-09-11T01:05:25","slug":"futbol","status":"publish","type":"post","link":"https:\/\/coloniaavellaneda.gob.ar\/web\/futbol\/","title":{"rendered":"Futbol"},"content":{"rendered":"<h2>FUTBOL<\/h2>\n<p>\t\tEn la tarde del domingo 05 de septiembre, en el Prado Espa\u00f1ol de nuestra ciudad, se jug\u00f3 la \u00faltima fecha de la Liga de F\u00fatbol de los Pueblos con la visita del Club Atl\u00e9tico San Rafael.\u00a0Fue un jornada positiva ya que los equipos de la Escuela Municipal de Deportes lograron finalizar entre los 3 primeros.\u00a0Resultados:\u00a0RESERVA MASCULINOColonia Avellaneda 0 &#8211; San Rafael 2PRIMERA MASCULINOColonia Avellaneda 5 &#8211; San Rafael 0RESERVA FEMENINO: Colonia Avellaneda 0 &#8211; San Rafael 2PRIMERA FEMENINOColonia Avellaneda 2 &#8211; San Rafael 1\u00a0<strong>\u00a1Agradecemos el acompa\u00f1amiento del p\u00fablico que se hizo presente y felicitamos a los chicos, las chicas y al cuerpo t\u00e9cnico!<\/strong>\t\t<\/p>\n<figure><img decoding=\"async\" src=\"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/09\/241490119_4368680719857400_7467441527351266358_n.jpg\" alt=\"241490119_4368680719857400_7467441527351266358_n\" \/><\/figure>\n<figure><img decoding=\"async\" src=\"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/09\/240575895_4368680586524080_6780891272611444703_n.jpg\" alt=\"240575895_4368680586524080_6780891272611444703_n\" \/><\/figure>\n<p>\t\t\t\t\t\tAnterior<br \/>\n\t\t\t\t\t\tSiguiente<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FUTBOL En la tarde del domingo 05 de septiembre, en el Prado Espa\u00f1ol de nuestra ciudad, se jug\u00f3 la \u00faltima fecha de la Liga de F\u00fatbol de los Pueblos con la visita del Club Atl\u00e9tico San Rafael.\u00a0Fue un jornada positiva ya que los equipos de la Escuela Municipal de Deportes lograron finalizar entre los 3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4327,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[7],"tags":[],"class_list":["post-4326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/4326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/comments?post=4326"}],"version-history":[{"count":0,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/4326\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/media?parent=4326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/categories?post=4326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/tags?post=4326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}