{"id":4386,"date":"2021-09-15T17:16:03","date_gmt":"2021-09-15T17:16:03","guid":{"rendered":"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/?p=4386"},"modified":"2021-09-15T17:16:03","modified_gmt":"2021-09-15T17:16:03","slug":"primavera-estudiantil","status":"publish","type":"post","link":"https:\/\/coloniaavellaneda.gob.ar\/web\/primavera-estudiantil\/","title":{"rendered":"Primavera Estudiantil"},"content":{"rendered":"<h2>Primavera estudiantil en Colonia Avellaneda<\/h2>\n<p>En el marco de los festejos por el d\u00eda del estudiante, la municipalidad de Colonia Avellaneda invita a participar de la Primavera estudiantil 2021.&nbsp;<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t5c\/1\/16\/1f5d3.png\" alt=\"&#x1f5d3;&#xfe0f;\" width=\"16\" height=\"16\"> El <strong>martes 21<\/strong> de septiembre a partir de las <strong>14:00hs<\/strong> en el Prado Espa\u00f1ol de nuestra ciudad los esperamos para pasar una tarde distinta, con actividades, sorteos y bandas en vivo.&nbsp;<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9e\/1\/16\/1f3b5.png\" alt=\"&#x1f3b5;\" width=\"16\" height=\"16\"> Pont a Bailar<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t1f\/1\/16\/1f3b6.png\" alt=\"&#x1f3b6;\" width=\"16\" height=\"16\"> La pi\u00f1a evolution&nbsp;<strong>No te lo podes perder<\/strong> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t21\/1\/16\/1f91e_1f3fc.png\" alt=\"&#x1f91e;&#x1f3fc;\" width=\"16\" height=\"16\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t96\/1\/16\/1f49c.png\" alt=\"&#x1f49c;\" width=\"16\" height=\"16\">&nbsp;El prado Espa\u00f1ol estar\u00e1 abierto desde las 9:00hs<br \/>\n<img decoding=\"async\" src=\"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/09\/241856719_4387183578007114_8485457658395255015_n.jpg\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/09\/241856719_4387183578007114_8485457658395255015_n.jpg 512w, http:\/\/coloniaavellaneda.gob.ar\/wordpress\/wp-content\/uploads\/2021\/09\/241856719_4387183578007114_8485457658395255015_n-240x300.jpg 240w\" sizes=\"(max-width: 512px) 100vw, 512px\" width=\"512\" height=\"640\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Primavera estudiantil en Colonia Avellaneda En el marco de los festejos por el d\u00eda del estudiante, la municipalidad de Colonia Avellaneda invita a participar de la Primavera estudiantil 2021.&nbsp; El martes 21 de septiembre a partir de las 14:00hs en el Prado Espa\u00f1ol de nuestra ciudad los esperamos para pasar una tarde distinta, con actividades, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4387,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-4386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"_links":{"self":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/4386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/comments?post=4386"}],"version-history":[{"count":0,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/posts\/4386\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/media?parent=4386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/categories?post=4386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coloniaavellaneda.gob.ar\/web\/wp-json\/wp\/v2\/tags?post=4386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}